{"id":3383,"date":"2019-09-24T12:26:07","date_gmt":"2019-09-24T10:26:07","guid":{"rendered":"https:\/\/labeltech.ch\/neu-epson-colorworks-c6000-6500\/"},"modified":"2026-04-17T17:33:52","modified_gmt":"2026-04-17T15:33:52","slug":"neu-epson-colorworks-c6000-6500","status":"publish","type":"post","link":"https:\/\/labeltech.ch\/fr\/neu-epson-colorworks-c6000-6500\/","title":{"rendered":"Nouvelles imprimantes d&#8217;\u00e9tiquettes : Epson ColorWorks C6000\/6500"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-2244\" src=\"https:\/\/labeltech.ch\/wp-content\/uploads\/2019\/09\/unbenannt01_50_autoresize_770_244.jpg\" alt=\"\" width=\"770\" height=\"244\" srcset=\"https:\/\/labeltech.ch\/wp-content\/uploads\/2019\/09\/unbenannt01_50_autoresize_770_244-200x63.jpg 200w, https:\/\/labeltech.ch\/wp-content\/uploads\/2019\/09\/unbenannt01_50_autoresize_770_244-350x111.jpg 350w, https:\/\/labeltech.ch\/wp-content\/uploads\/2019\/09\/unbenannt01_50_autoresize_770_244-400x127.jpg 400w, https:\/\/labeltech.ch\/wp-content\/uploads\/2019\/09\/unbenannt01_50_autoresize_770_244-500x158.jpg 500w, https:\/\/labeltech.ch\/wp-content\/uploads\/2019\/09\/unbenannt01_50_autoresize_770_244-600x190.jpg 600w, https:\/\/labeltech.ch\/wp-content\/uploads\/2019\/09\/unbenannt01_50_autoresize_770_244-700x222.jpg 700w, https:\/\/labeltech.ch\/wp-content\/uploads\/2019\/09\/unbenannt01_50_autoresize_770_244-705x223.jpg 705w, https:\/\/labeltech.ch\/wp-content\/uploads\/2019\/09\/unbenannt01_50_autoresize_770_244-768x243.jpg 768w, https:\/\/labeltech.ch\/wp-content\/uploads\/2019\/09\/unbenannt01_50_autoresize_770_244.jpg 770w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<p>Epson a annonc\u00e9 l&#8217;ajout de quatre nouvelles imprimantes d&#8217;\u00e9tiquettes ColorWorks \u00e0 sa gamme : ColorWorks CW-C6000Ae, CW-C6000Pe, CW-C6500Ae et CW-C6500Pe. Ces imprimantes d&#8217;\u00e9tiquettes \u00e0 la demande r\u00e9pondent aux besoins des clients de petite et moyenne taille dans diff\u00e9rents secteurs (alimentation, chimie, boissons, horticulture, logistique, etc.) La ligne de produits comprend des mod\u00e8les \u00e0 coupe automatique (Ae) et des fonctions de pelage automatique (Pe) permettant de gagner du temps, qui retirent automatiquement le papier support d&#8217;\u00e9tiquettes et s&#8217;int\u00e8grent de mani\u00e8re transparente dans les syst\u00e8mes de production existants.  <\/p>\n<p><iframe src=\"https:\/\/www.youtube-nocookie.com\/embed\/E5aM3fVGJPs\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2>Epson ColorWorks C6000\/C6500<\/h2>\n<p>Si vous voulez des \u00e9tiquettes d&#8217;une qualit\u00e9 exceptionnelle, les imprimantes d&#8217;\u00e9tiquettes couleur de la s\u00e9rie C6000 d&#8217;Epson sont le choix qui s&#8217;impose. Elles offrent une grande fiabilit\u00e9 \u00e0 des co\u00fbts d&#8217;impression r\u00e9duits. Pour des largeurs d&#8217;impression jusqu&#8217;\u00e0 108 mm, l&#8217;Epson ColorWorks C6000 est convaincante, pour des largeurs d&#8217;impression jusqu&#8217;\u00e0 212 mm, Epson propose l&#8217;imprimante ColorWorks C6500. Dans un souci d&#8217;\u00e9conomie et de respect de l&#8217;environnement, les quatre cartouches d&#8217;encre, magenta, jaune, cyan et noir, d&#8217;un volume de 80 ml, sont rempla\u00e7ables individuellement. Avec 800 buses par couleur, la qualit\u00e9 photo n&#8217;est pas une utopie. Avec les imprimantes d&#8217;\u00e9tiquettes couleur de la famille Epson ColorWorks, vous ne cr\u00e9ez pas seulement des \u00e9tiquettes couleur de la plus haute qualit\u00e9, mais elles sont \u00e9galement r\u00e9sistantes au maculage et \u00e0 l&#8217;eau. Gr\u00e2ce \u00e0 l&#8217;interface E\/S, les imprimantes peuvent \u00eatre facilement int\u00e9gr\u00e9es dans des syst\u00e8mes d&#8217;\u00e9tiquetage automatiques. Chaque mod\u00e8le offre \u00e9galement l&#8217;option d&#8217;un coupe-papier ou d&#8217;une peleuse int\u00e9gr\u00e9e pour d\u00e9coller les \u00e9tiquettes du support.       <\/p>\n<h3>Applications de la gamme Color Works C6000<\/h3>\n<ul>\n<li>Alimentation et boissons<\/li>\n<li>Produits non alimentaires<\/li>\n<li>Nourriture pour animaux<\/li>\n<li>\u00c9tiquetage d&#8217;emballages<\/li>\n<li>Produits chimiques<\/li>\n<li>Logistique<\/li>\n<li>Horticulture<\/li>\n<\/ul>\n<h3>Sp\u00e9cifications du p\u00e9riph\u00e9rique :<\/h3>\n<table>\n<thead>\n<tr>\n<th><strong>Mod\u00e8le<\/strong><\/th>\n<th><strong>ColorWorksC6000<\/strong><\/th>\n<th><strong>ColorWorksC6500<\/strong><\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>R\u00e9solution (dpi)<\/td>\n<td>1.200 x 1.200 dpi<\/td>\n<td>1.200 x 1.200 dpi<\/td>\n<\/tr>\n<tr>\n<td>Couleurs d&#8217;encre<\/td>\n<td>4 couleurs<\/td>\n<td>4 couleurs<\/td>\n<\/tr>\n<tr>\n<td>Capacit\u00e9 d&#8217;encre<\/td>\n<td>80ml<\/td>\n<td>80ml<\/td>\n<\/tr>\n<tr>\n<td><strong>Supports pris en charge<\/strong><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>\u00c9tiquette mate<\/td>\n<td>Oui<\/td>\n<td>Oui<\/td>\n<\/tr>\n<tr>\n<td>\u00c9tiquette de film mat<\/td>\n<td>Oui<\/td>\n<td>Oui<\/td>\n<\/tr>\n<tr>\n<td>\u00c9tiquette glossy<\/td>\n<td>Oui<\/td>\n<td>Oui<\/td>\n<\/tr>\n<tr>\n<td>\u00c9tiquette film glossy<\/td>\n<td>Oui<\/td>\n<td>Oui<\/td>\n<\/tr>\n<tr>\n<td>\u00c9tiquette haute brillance<\/td>\n<td>Oui<\/td>\n<td>Oui<\/td>\n<\/tr>\n<tr>\n<td>Connexion E\/S<\/td>\n<td>Standard<\/td>\n<td>Standard<\/td>\n<\/tr>\n<tr>\n<td>Direction de l&#8217;impression<\/td>\n<td>Bidirectionnel ou unidirectionnel<\/td>\n<td>Bidirectionnel ou unidirectionnel<\/td>\n<\/tr>\n<tr>\n<td>Longueur de l&#8217;\u00e9tiquette<\/td>\n<td>609,6 mm<\/td>\n<td>609,6 mm<\/td>\n<\/tr>\n<tr>\n<td>Dimensions<\/td>\n<td>340 x 565 x 326 mm<\/td>\n<td>444 x 512 x 326 mm<\/td>\n<\/tr>\n<tr>\n<td><strong>Vitesse d&#8217;impression<\/strong><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>300 x 600 ppp<\/td>\n<td>119mm\/sec.<\/td>\n<td>85mm\/sec.<\/td>\n<\/tr>\n<tr>\n<td>600 x 600 ppp<\/td>\n<td>75mm\/sec.<\/td>\n<td>49mm\/sec.<\/td>\n<\/tr>\n<tr>\n<td>600 x 1.200 dpi<\/td>\n<td>18mm\/sec.<\/td>\n<td>13mm\/sec.<\/td>\n<\/tr>\n<tr>\n<td>1 200 x 1 200 dpi<\/td>\n<td>8mm\/sec.<\/td>\n<td>6mm\/sec.<\/td>\n<\/tr>\n<tr>\n<td>Diam\u00e8tre ext\u00e9rieur des rouleaux<\/td>\n<td>203,2mm\/ 8 pouces<\/td>\n<td>152,4mm\/ 6 pouces<\/td>\n<\/tr>\n<tr>\n<td>Largeur du papier<\/td>\n<td>25,4 \u00e0 112 mm<\/td>\n<td>25,4 \u00e0 215,9 mm<\/td>\n<\/tr>\n<tr>\n<td>Largeur d&#8217;impression<\/td>\n<td>jusqu&#8217;\u00e0 108 mm<\/td>\n<td>jusqu&#8217;\u00e0 211,9 mm<\/td>\n<\/tr>\n<tr>\n<td>Ports<\/td>\n<td>USB 2.0 type A\/B<\/td>\n<td>USB 2.0 type A\/B<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Interface Ethernet (100 Base-TX\/10 Base-T)<\/td>\n<td>Interface Ethernet (100 Base-TX\/10 Base-T)<\/td>\n<\/tr>\n<tr>\n<td>Poids<\/td>\n<td>45 kg<\/td>\n<td>55kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>La facilit\u00e9 d&#8217;utilisation de la gamme ColorWorks C6000<\/h3>\n<ul>\n<li>Insertion facile des m\u00e9dias<\/li>\n<li>\u00c9limination facile des bourrages papier en ouvrant compl\u00e8tement le capot papier, flexible de tous les c\u00f4t\u00e9s.<\/li>\n<li>Grand \u00e9cran LCD couleur<\/li>\n<li>Int\u00e9gration dans SAP<\/li>\n<li>Compatible avec Windows, Linux et Mac\/iOS<\/li>\n<li>Pilotes propri\u00e9taires pour ESC\/Label, Bar Tender, CodeSoft et NiceLabel<\/li>\n<\/ul>\n<h2>Pourquoi acheter une imprimante Epson ?<\/h2>\n<p>La soci\u00e9t\u00e9 Epson veille au d\u00e9veloppement durable dans ses usines, ses entrep\u00f4ts et ses m\u00e9thodes de transport. Parall\u00e8lement, ils aident \u00e9galement les consommateurs \u00e0 la maison en g\u00e9rant les d\u00e9chets et en recyclant les produits. C&#8217;est ce qu&#8217;explique le pr\u00e9sident d&#8217;Epson Europe, M. Kazuyoshi Yamamoto :  <\/p>\n<p>&#8220;Nous nous sommes engag\u00e9s \u00e0 offrir aux entreprises de toute l&#8217;Europe une alternative \u00e9cologique claire dans le choix des produits qu&#8217;elles utilisent. J&#8217;entends tous les jours des clients dire qu&#8217;ils ont besoin d&#8217;une technologie plus \u00e9cologique, plus \u00e9conomique et plus efficace. C&#8217;est exactement ce qu&#8217;Epson a fourni, mais la v\u00e9ritable performance, sans parler des b\u00e9n\u00e9fices cumulatifs, est \u00e0 mettre au cr\u00e9dit de nos clients professionnels, car ils ont pris la d\u00e9cision de passer de la technologie laser \u00e0 la <strong>technologie jet d&#8217;encre <\/strong>&#8220;.  <\/p>\n<h2>La responsabilit\u00e9 RSE d&#8217;Epson (CSR= Corporate Social Responsibility)<\/h2>\n<p>Epson d\u00e9veloppe des produits respectueux de l&#8217;environnement. De la conception au produit fini et au processus de recyclage, Epson a toujours le d\u00e9veloppement durable \u00e0 l&#8217;esprit. Epson aide ses clients \u00e0 identifier les avantages environnementaux offerts par la technologie, qu&#8217;il s&#8217;agisse d&#8217;\u00e9conomies d&#8217;\u00e9nergie gr\u00e2ce \u00e0 de nouvelles technologies d&#8217;impression ou de nouvelles solutions d&#8217;impression num\u00e9rique sur textile respectueuses de l&#8217;environnement. Epson s&#8217;engage \u00e0 respecter les 17 lignes de d\u00e9veloppement durable des Nations Unies et met l&#8217;accent sur l&#8217;\u00e9conomie circulaire.   <\/p>\n<h2>Pourquoi Epson s&#8217;appelle-t-il Epson ?<\/h2>\n<p>La soci\u00e9t\u00e9 Shinshu Seiko Co, un pr\u00e9curseur de la soci\u00e9t\u00e9 Epson, a d\u00e9velopp\u00e9 en 1968 la premi\u00e8re imprimante miniature appel\u00e9e EP-101. Il ne s&#8217;agissait pas vraiment d&#8217;une imprimante telle que nous la connaissons aujourd&#8217;hui, mais d&#8217;un groupe d&#8217;impression destin\u00e9 \u00e0 l&#8217;impression avec d&#8217;autres machines. La demande pour l&#8217;EP-101 \u00e9tait telle qu&#8217;en 1975, le mod\u00e8le suivant a \u00e9t\u00e9 lanc\u00e9, sous le nom de Son of EP-101. Cette imprimante a donn\u00e9 son nom \u00e0 la soci\u00e9t\u00e9 Epson.<\/p>\n<p>N&#8217;h\u00e9sitez pas \u00e0 nous contacter si vous avez des questions sur les nouveaux produits !<\/p>\n<p>Vous trouverez ce produit dans la cat\u00e9gorie <a href=\"https:\/\/labeltech.ch\/fr\/produits\/imprimante-couleur\/\">Imprimantes couleur<\/a>.<\/p>\n<p>Les C6000AE et C6500 \u00e9largissent la gamme ColorWorks d&#8217;<a href=\"https:\/\/labeltech.ch\/fr\/partenaire\/epson\/\" title=\"Epson - Partenaire Colour Label+ Gold pour les imprimantes d'\u00e9tiquettes couleur professionnelles et les solutions d'impression\">Epson<\/a> vers le haut. La <a href=\"https:\/\/labeltech.ch\/fr\/produkt\/epson-colorworks-c4000e\/\" title=\"Epson ColorWorks C4000e - Imprimante d'\u00e9tiquettes couleur compacte pour compl\u00e9ter la s\u00e9rie C6000\">ColorWorks C4000e<\/a> est \u00e9galement une solution d&#8217;entr\u00e9e de gamme \u00e9conomique. Tous les mod\u00e8les sont r\u00e9pertori\u00e9s dans la cat\u00e9gorie <a href=\"https:\/\/labeltech.ch\/fr\/produits\/imprimante-couleur\/\" title=\"Aper\u00e7u des imprimantes d'\u00e9tiquettes couleur - Epson ColorWorks et autres marques dans la gamme\">Imprimantes couleur<\/a>. Pour les entreprises commerciales, nos <a href=\"https:\/\/labeltech.ch\/fr\/solutions-dimpression\/commerce\/\" title=\"Solutions d'impression pour le commerce - \u00c9tiquetage couleur pour les produits, les promotions et l'exp\u00e9dition\">solutions d&#8217;impression pour le commerce<\/a> offrent des exemples pratiques plus d\u00e9taill\u00e9s.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Epson a annonc\u00e9 l&#8217;ajout de quatre nouvelles imprimantes d&#8217;\u00e9tiquettes ColorWorks  [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":3384,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89],"tags":[],"class_list":["post-3383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-fr"],"_links":{"self":[{"href":"https:\/\/labeltech.ch\/fr\/wp-json\/wp\/v2\/posts\/3383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labeltech.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labeltech.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labeltech.ch\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/labeltech.ch\/fr\/wp-json\/wp\/v2\/comments?post=3383"}],"version-history":[{"count":1,"href":"https:\/\/labeltech.ch\/fr\/wp-json\/wp\/v2\/posts\/3383\/revisions"}],"predecessor-version":[{"id":11608,"href":"https:\/\/labeltech.ch\/fr\/wp-json\/wp\/v2\/posts\/3383\/revisions\/11608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labeltech.ch\/fr\/wp-json\/wp\/v2\/media\/3384"}],"wp:attachment":[{"href":"https:\/\/labeltech.ch\/fr\/wp-json\/wp\/v2\/media?parent=3383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labeltech.ch\/fr\/wp-json\/wp\/v2\/categories?post=3383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labeltech.ch\/fr\/wp-json\/wp\/v2\/tags?post=3383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}